{"text_format":"1","workbook":"xlsx","n_sheets":7,"sheets":["Control cambios","Datos Generales","Productos","tipos","Hoja2","Proveedores","Resumen Productos "],"not_rendered":{"charts":0,"images":1,"macros":1,"external_links":0,"defined_names":201,"comments":0,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Control cambios","index":0,"n_rows":7,"n_cols":3,"rows_kept":7,"cut":false,"hidden":false,"merged":[]}
["F495-02"]
[]
[]
[]
[]
[]
[null,"Fecha","Descripción de cambios"]

{"sheet":"Datos Generales","index":1,"n_rows":116,"n_cols":8,"rows_kept":116,"cut":false,"hidden":false,"merged":[[59,3,59,5],[60,3,60,5],[61,3,61,5],[62,3,62,5],[63,3,63,5],[85,1,85,5],[58,3,58,5],[83,1,83,7],[96,2,96,5],[73,6,74,7],[75,6,76,7],[97,2,97,5],[75,4,76,5],[61,6,61,7],[62,6,62,7],[63,6,63,7],[61,1,61,2],[62,1,62,2],[63,1,63,2],[98,2,98,5],[88,1,88,7],[92,6,92,7],[92,2,92,5],[93,2,93,5],[94,2,94,5],[95,2,95,5],[67,6,69,7],[85,6,85,7],[77,6,79,7],[82,1,82,7],[66,4,66,5],[67,4,69,5],[70,4,72,5],[73,4,74,5],[70,6,72,7],[45,2,45,4],[46,2,46,4],[47,2,47,4],[46,5,46,6],[47,5,47,6],[87,1,87,7],[59,1,59,2],[60,1,60,2],[59,6,59,7],[60,6,60,7],[55,1,55,7],[56,1,56,7],[57,1,57,7],[86,1,86,5],[86,6,86,7],[65,1,65,7],[58,1,58,2],[66,1,66,3],[66,6,66,7],[67,1,69,3],[70,1,72,3],[73,1,74,3],[75,1,76,3],[77,1,79,3],[42,1,42,7],[44,2,44,3],[25,1,25,5],[23,6,23,7],[32,1,32,7],[33,1,33,3],[33,5,33,7],[34,5,34,7],[34,1,34,3],[0,5,0,7],[29,1,29,7],[26,2,26,3],[14,1,14,7],[1,1,2,7],[4,1,4,7],[8,1,8,7],[5,1,6,7],[9,1,9,7],[15,6,15,7],[21,1,21,7],[16,6,16,7],[16,1,16,5],[18,6,18,7],[18,2,18,5],[11,1,11,7],[0,1,0,3],[15,1,15,5],[23,1,23,5],[115,6,115,7],[12,1,12,7],[22,1,22,7],[24,1,24,7],[19,6,19,7],[25,6,25,7],[26,6,26,7],[51,1,53,7],[50,1,50,7],[91,1,91,7],[36,3,36,7],[35,3,35,5],[35,6,35,7],[35,1,35,2],[36,1,36,2],[17,1,17,7],[19,1,19,3],[20,1,20,7],[37,1,37,7],[38,1,38,7],[39,1,39,7],[58,6,58,7],[44,5,44,6],[45,5,45,6]]}
[null,"  SOHISCERT ",null,null,null,"Norma UNE 66500 Diciembre 2017"]
[null," SOLICITUD DE CERTIFICACIÓN INSUMOS\n UTILIZABLES EN PRODUCCIÓN VEGETAL ECOLÓGICA "]
[]
[]
[null,"ALCANCE DE CERTIFICACIÓN "]
[]
[]
[]
[null,"DESCRIPCIÓN ACTIVIDAD "]
[]
[]
[null,"TIPO DE PRODUCCIÓN "]
[null,"                                                                  "]
[]
[null,"IDENTIFICACIÓN DEL OPERADOR SOLICITANTE  "]
[null,"Razón Social o Nombre: ",null,null,null,null,"C.I.F/N.I.F: "]
[null,"Representante de la empresa: ",null,null,null,null,"NIF:"]
[null,"Dirección: "]
[null,"Cód. postal: ","Municipio: ",null,null,null,"Provincia: "]
[null,"Teléfono:",null,null,null," "]
[null,"E-mail:"]
[null,"Interlocución SOHISCERT"]
[null,"Persona que atiende auditorias:"]
[null,"E-mail:",null,null,null,null,"Tef.:"]
[null,"Persona que recibe notificaciones a través del área privada Web"]
[null,"E-mail:",null,null,null,null,"Tef.:"]
[]
[]
[]
[null,"IDENTIFICACIÓN DE LAS INSTALACIONES (Duplicar tantas veces como instalaciones posea)\n\n"]
[null,"Nº instalaciones",1]
[null,"(Seleccione Actividad)"]
[null,"Nombre:"]
[null,"C.I.F.: ",null,null,null,"Responsable: "]
[null,"Dirección: ",null,null,null,"Cargo:"]
[null,"Cód. postal: ",null,"Municipio:  ",null,null,"Provincia: "]
[null,"Teléfono:",null,"E-mail:"]
[null,"Código NIMA "]
[null,"Código LER "]
[null,"Código SANDACH"]
[]
[]
[null," SUBCONTRATAS"]
[null,"Realiza alguna fase intermedia del proceso en otras instalaciones ajenas                 Sí            No"]
[null,"Nombre de la instalación externa","Titular",null,null,"Proceso que le realiza",null,"Productos"]
[]
[]
[]
[]
[]
[null,"    ANTERIOR ORGANISMO DE CONTROL"]
[null,"          Sí, ha estado certificado anteriormente bajo Norma UNE, con el Organismo de Control (OC) \n          No\n          Fecha de baja en el otro OC __/__/____\n          Fecha de caducidad del certificado  __/__/____\n"]
[]
[]
[]
[null," TRAZABILIDAD"]
[null,"(Descripción en caso de no adjuntar protocolo de trazabilidad)"]
[]
[null,"Etapa",null,"Tipología nº de lote",null,null,"Descripción elementos"]
[null,"Recepción"]
[null,"Almacenamiento"]
[null,"Manipulación "]
[null,"Envasado / Etiquetado"]
[null,"Expedición"]
[]
[null,"  SISTEMA DE AUTOCONTROL"]
[null,"Tipo de análisis ",null,null,"Frecuencia ",null,"Laboratorio "]
[null,"      Análisis de residuos de productos fitosanitarios incluyendo sustancias activas con las que se trabaje en las instalaciones.  "]
[]
[]
[null,"      Fosfetil Al, fosfonatos, ácido fosfónico y sus sales. "]
[]
[]
[null,"     Percloratos  "]
[]
[null,"     Metales pesados "]
[]
[null,"     Análisis de riqueza "]
[]
[]
[]
[]
[null,"  MEDIDAS DE REDUCCIÓN RIESGO"]
[null,"¿Existen riesgos medios o altos según lo descrito en norma UNE 142500 o UNE 315500?\nSi                                      No "]
[null,"        Medidas aplicadas:"]
[null,"        Separación física e identificación de zonas ECO / No ECO",null,null,null,null,"    Toma de muestras"]
[null,"        Limpieza previa",null,null,null,null,"    Evaluación de proveedores"]
[null,"        Otras. Indique cuáles:"]
[]
[]
[]
[null,"SEPARACIÓN Y LIMPIEZA"]
[null,"Zona / Etapa","Descripción",null,null,null,"Medida de separación"]
[null,"Transporte de recepción",null,null,null,null,"   Espacial         Temporal"]
[null,"Recepción",null,null,null,null,"   Espacial         Temporal"]
[null,"Almacenamiento",null,null,null,null,"   Espacial         Temporal"]
[null,"Manipulación ",null,null,null,null,"   Espacial         Temporal"]
[null,"Envasado / Etiquetado",null,null,null,null,"   Espacial         Temporal"]
[null,"Transporte de expedición",null,null,null,null,"   Espacial         Temporal"]
[]
[null,"Documentación a aportar :"]
[]
[]
[null,"    "]
[]
[null,"    "]
[null,"    "]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"Fecha solicitud",null,null,null,null,"dd/mm/aaaa"]

{"sheet":"Productos","index":2,"n_rows":4,"n_cols":31,"rows_kept":4,"cut":false,"hidden":false,"merged":[[2,20,3,20],[2,1,3,1],[2,2,3,2],[2,30,3,30],[0,0,1,30],[2,22,3,22],[2,23,3,23],[2,27,2,29],[2,24,3,24],[2,25,3,25],[2,9,2,19],[2,26,3,26],[2,21,3,21],[2,0,3,0],[2,3,3,3],[2,5,3,5],[2,6,3,6],[2,7,2,8],[2,4,3,4]]}
["DECLARACIONES DE PRODUCTOS \nIndique los productos objeto de certificación. \nLos campos marcados con asterisco se deben cumplimentar a partir de la selección de las opciones proporcionadas en los desplegables "]
[]
["Fecha Solicitud Alta ","Fecha Solicitud Baja ","Motivo Baja (*)","Categoria de producto (*)","Tipo (*) ","Denominación Tipo (*) ","Producto \n(Marca comercial) ","Registro MAPAMA",null,"Composición ",null,null,null,null,null,null,null,null,null,null,"Instalación Propia","Actividad de Instalación Propia (*)","Instalación Externa 1\n(Instalación ajena en la que se lleva a cabo parte del proceso)\n(Nombre empresa y Dirección)","Actividad de Instalación Externa 1 (*)","Instalación Externa 2\n(Instalación ajena en la que se lleva a cabo parte del proceso)\n(Nombre empresa y Dirección)","Actividad de Instalación Externa 2 (*)","Presentación ","Homologación",null,null,"Observaciones\n(Breves comentarios aclaratorios, p.ej. Envío de documentación confidencial por tercero, etc..)"]
[null,null,null,null,null,null,null,"Si /No / En trámite (*) ","Nº ","Materia prima (*)","% peso","Materia prima (*)","% peso","Materia prima (*)","% peso","Materia prima (*)","% peso","Otros","% peso","Riqueza declarada",null,null,null,null,null,null,null,"Homólogo (*)","Producto homólogo","Empresa"]

{"sheet":"tipos","index":3,"n_rows":132,"n_cols":181,"rows_kept":132,"cut":false,"hidden":true,"merged":[]}
[null,null,null,null,null,null,null,1,2,3,4,5,null,1.1000000000000001,1.2,1.3,1.4,null,null,null,null,null,null,null,1,2,3,4,5,6,7,8,9,11,12,14,15,16,17,18,19,20,21,22,23,24,25,26,27,28,29,30,31,32,33,34,35,36,37,38,39,40,41,42,43,44,45,46,47,48,49,null,null,null,null,null,null,50,51,52,53,54,56,55,null,57,58,59,60,62,63,64,65,66,67,68,69,70,71,72,73,74,75,76,77,78,79,80,81,82,83,84,85,86,87,88,89,90,91,92,93,94,95,96,97,98,99,100,101,102,103,104,105,106,107,108,109,110,111,112,113,114,115,116,117,118,119,120,121,122,123,124,125,126,127,128,129,null,null,null,null,null,null,null,null,null,null,null,null,null,128,null,null,"(Seleccione Actividad)"]
["Categoria de producto ","Tipo","Denominación_Tipo_","Registro MAPAMA","Materia prima",null,"Seleccione Categoria de producto ","Fertilizante ","Enmiendas","Sustrato","Fitosanitarios","Sustancias_básicas","Abono_inorgánico","Abono_orgánico","Abono_organo_mineral","Abono_especial","Abono_CE","Enimienda_caliza","Enimenda_orgánica","Sustrato_","Fitosanitarios_","Sustancias_básicas_","_1.1.3.01_Solución_potásica","_1.1.4.04_Solución_PK","2.1.01_Abono_orgánico_nitrogenado_de_origen_animal","_2.1.02_Abono_orgánico_nitrogenado_de_origen_vegetal","_2.1.03_Abono_orgánico_nitrogenado_de_origen_animal_y_vegetal","_2.2.01_Abono_orgánico_fosfatado_de_origen_animal","_2.3.01_Abono_orgánico_NPK_de_origen_animal","_2.3.02_Abono_orgánico_NPK_de_origen_animal_y_vegetal","_2.4.01_Abono_orgánico_NP_de_origen_animal","_2.4.02_Abono_orgánico_NP_de_origen_animal_y_vegetal","_2.5.01_Abono_orgánico_NK_de_origen_vegetal","_3.1.02_Abono_órgano_mineral_nitrogenado_con_turba","_3.1.03_Abono_órgano_mineral_nitrogenado_con_lignito_o_leonardita","_3.1.05_Abono_órgano_mineral_nitogenado_líquido_con_turba","_3.2.01_Abono_órgano_mineral_NPK","_3.2.02_Abono_órgano_mineral_NPK_con_turba","_3.2.03_Abono_órgano_mineral_NPK_con_lignito_o_leonardita","_3.2.04_Abono_órgano_mineral_NPK_con_o_sin_turba_con_fosfato_roca","_3.3.01_Abono_órgano_mineral_NPK_líquido","_3.3.02_Abono_órgano_mineral_NPK_líquido_con_turba","_3.4.01_Abono_órgano_mineral_NP","_3.4.02_Abono_órgano_mineral_NP_con_turba","_3.4.03_Abono_órgano_mineral_NP_con_lignito_o_leonardita","_3.4.04_Abono_órgano_mineral_NP_con_o_sin_turba_con_fosfato_roca","_3.5.01__Abono_órgano_mineral_NP_líquido","_3.5.02__Abono_órgano_mineral_NP_líquido_con_turba","_3.6.01_Abono_órgano_mineral_NK","_3.6.02_Abono_órgano_mineral_NK_con_turba","_3.6.03__Abono_órgano_mineral_NK_con_lignito_o_leonardita","_3.7.01__Abono_órgano_mineral_NK_líquido","_3.7.02_Abono_órgano_mineral_NK_líquido_con_turba","_3.8.01_Abono_órgano_mineral_PK","_3.8.02_Abono_órgano_mineral_PK_con_turba","_3.8.03_Abono_órgano_mineral_PK_con_lignito_o_leonardita","_3.8.04_Abono_órgano_mineral_PK_con_o_sin_turba_con_fosfato_roca","_3.9.01_Abono_órgano_mineral_PK_líquido","_3.9.02_Abono_órgano_mineral_PK_líquido_con_turba","_4.1.01_Aminoácidos","_4.1.02_Abono_con_aminoácidos","_4.1.03_Ácidos_húmicos","_4.1.04_Abonos_con_ácidos_húmicos","_4.1.05_Extracto_de_algas_sólido","_4.1.06_Extracto_de_algas_líquidos","_4.1.07a__Abono_sólido_con_extracto_de_algas","_4.1.07b__Abono_líquido_con_extracto_de_algas","_4.1.11_Mezcla_sólida_de_aminoácidos_y_extracto_de_algas","_4.1.12_Mezcla_líquida_de_aminoácidos_y_extracto_de_algas","_4.1.13_Abono_sólido_con_extracto_de_algas_y_aminoácidos","_4.1.14_Abono_líquido_con_extracto_de_algas_y_aminoácidos","_4.4.01_Micorrizas","_4.4.02_Abono_con_micorrizas","_4.4.03_Microorganismos_no_micorrícicos","_ 4.4.04 Abono con microorganismos no micorrícicos","_4.4.05_Mezcla_de_microorganismos","_4.4.06_Abono_con_microorganismos","_A.2.6_Fosfato_aluminocálcico","_A.2.7_Fosfato_roca_blanda","_A.3.1_Sal_potásica_en_bruto","_A.3.6_Sulfato_potásico_con_sales_de_magnesio","_D.1_Sulfato_cálcico","_D.2_Solución_de_cloruro_de_calcio","_D.3_Azufre_elemental","_D.4._Sulfato_de_magnesio","_E._Abonos_inorgánicos_que_contienen_micronutrientes","_G.1._Enmiendas_naturales","_G.3.1a_y_1b__Caliza_dolomítica_estandar_y_calidad_superior","_A.2.1_Escorias_de_deforestación","_5.02_Enmienda_caliza_Margas","_5.03_Enmienda_caliza_Carbonato_magnésico_","_5.04_Enmienda_caliza_Oxido_de_magnesio_magnesita","_6.01_Enmienda_orgánica_húmica","_6.02_Enmienda_orgánica_Compost","_6.03_Enmienda_orgánica_Compost_vegetal","_6.04_Enmienda_orgánica_Compost__de_estiércol","_6.05_Enmienda_orgánica_Vermicompost","_6.06_Enmienda_orgánica_Turba_de_musgo_Tipo_Sphagnum","_6.07_Enmienda_orgánica_Turba_herbácea","_6.08_Alperujo_desecado","_6.09_Compost_de_alperujo","_1.1_Compost","_1.3_Compost_de_estiércol","_1.10_Turba_de_Sphagnum","_1.11_Turba_herbácea","_1.12_Vermicompost_o_húmus_de_lombriz","_1.4_Compost_vegetal","_2.1_Arcilla","_2.2_Arcilla_cocida","_2.3_Arcilla_expandida","_2.4_Arcilla_granulada_","_2.5_Arena_y_gravillas","_2.6_Arenas_y_gravillas_silíceas","Extracto_de_ajo","Azadiractin","Ceras_","COS_OGA","Proteínas_hidrolizadas","Laminarín","Maltodextrina","Feromonas","Aceites_vegetales","Piretrinas","Cuasia_","Repelente_de_origen_animal_o_vegetal_grasa_de_ovino","Corteza_de_sauce_salix_cortex","Eugenol_terpenos","Geraniol_terpenos","Timol_terpenos","Lecitina_de_soja_sustancia_básica_a_base_de_alimentos","Microorganismos","Spinosad","Cerevisane","Silicato_de_aluminio._Caolín","Hidróxido_de_calcio","Dióxido_de_carbono","Hidróxido_cuprico_Compuesto_de_cobre","Oxicloruro_de_cobre_compuesto_de_cobre","Óxido_cuproso_compuesto_de_cobre","Óxido_de_cobre_compuesto_de_cobre","Sulfato_cuprocálcico_compuesto_de_cobre_caldo_bordelés","Sulfato_tribásico_de_cobre_compuesto_de_cobre","Fosfato_diámonico","Etileno","Sales_potasicas_de_ácidos_grasos_vegetales","Fosfato_férrico","Peróxido_de_hidrógeno","Tierra_de_diatomeas_","Polisulfuro_de_calcio","Aceite_de_parafina","Hidrógenocarbonato_de_potasio","Deltametrín_Piretroides","Lambda_cihalotrin_piretroides","Arena_de_cuarzo","Cloruro_de_sodio","Azufre","Aceite _de_cebolla","Aceite_de_girasol","Carbón_vegetal_arcilloso","Cerveza","Quitosano_Clorhidrato_de_quitosano","Equisetum_arvense_Cola_de_caballo","Frutuosa","Lecitina","Polvo_de_semillas_de_mostaza","Sacarosa","Salix_spp_cortex_Corteza_de_sauce","Suero","Urtica_spp_Ortiga","Vinagre",null,null,null,"Producción",null,"Sí"]
["Fertilizante ","Abono orgánico","2.1.01_Abono_orgánico_nitrogenado_de_origen_animal","Sí/No/En trámite","Ver hoja Materias primas por tipo",2,"Fertilizante ","Seleccione Tipo","Enimenda_orgánica","Sustrato_","Fitosanitarios_","Sustancias_básicas_","_1.1.3.01_Solución_potásica","_2.1.01_Abono_orgánico_nitrogenado_de_origen_animal","_3.1.02_Abono_órgano_mineral_nitrogenado_con_turba","_4.1.01_Aminoácidos","Seleccione Denominación Tipo","_5.02_Enmienda_caliza_Margas","_6.01_Enmienda_orgánica_húmica","_1.1_Compost","Aceite_de_parafina","Aceite_de_cebolla","Sal potásica en bruto","Fosfato natural blando","Digerido_ biogá_ con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Ácidos húmicos y fúlvicos","Ácidos húmicos y fúlvicos","Algas y productos de algas","Algas y productos de algas","Algas y productos de algas","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Microorganismos","Microorganismos","Microorganismos","Microorganismos","Microorganismos","Microorganismos","Fosfato aluminocálcico","Fosfato natural blando ","Sal potásica en bruto","Sulfato de potasio que puede contener sal de magnesio","Sulfato de calcio (yeso)","Solución de cloruro de calcio","Azufre elemental","Sulfato de magnesio","Ácido Bórico","Carbonato de Calcio","Cal industrial procedente de la producción de azúcar","Escorias de desforación","Carbonato de Calcio","Carbonato de Calcio y magnesio","Carbonato de Calcio y magnesio","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Extracto_de_ajo","Azadiractin","Cera de Abeja","COS_OGA","Proteínas_hidrolizadas","Laminarín","Maltodextrina","Feromonas","Aceite_de_citronela","Piretrinas","Cuasia_","Repelente_de_origen_animal_o_vegetal_grasa_de_ovino","Corteza_de_sauce_salix_cortex","Eugenol_terpenos","Geraniol_terpenos","Timol_terpenos","Lecitina_de_soja_sustancia_básica_a_base_de_alimentos","Microorganismos","Spinosad","Cerevisane","Silicato_de_aluminio._Caolín","Hidróxido_de_calcio","Dióxido_de_carbono","Hidróxido_cuprico_Compuesto_de_cobre","Oxicloruro_de_cobre_compuesto_de_cobre","Óxido_cuproso_compuesto_de_cobre","Óxido_de_cobre_compuesto_de_cobre","Sulfato_cuprocálcico_compuesto_de_cobre_caldo_bordelés","Sulfato_tribásico_de_cobre_compuesto_de_cobre","Fosfato_diámonico","Etileno","Sales_potasicas_de_ácidos_grasos_vegetales","Fosfato_férrico","Peróxido_de_hidrógeno","Tierra_de_diatomeas_","Polisulfuro_de_calcio","Aceite_de_parafina","Hidrógenocarbonato_de_potasio","Deltametrín_Piretroides","Lambda_cihalotrin_piretroides","Arena_de_cuarzo","Cloruro_de_sodio","Azufre","Aceite de cebolla","Aceite de girasol","Carbón vegetal arcilloso","Cerveza","Quitosano (Clorhidrato de quitosano)","Equisetum arvense (Cola de caballo)","Frutuosa","Lecitina","Polvo de semillas de mostaza","Sacarosa","Salix spp cortex (Corteza de sauce)","Suero","Urtica spp (Ortiga)","Vinagre","No",null,null,"Envasado",null,"No",null,null,null,null,"Producto no comercializado "]
["Fertilizante ","Abono orgánico","2.1.02_Abono_orgánico_nitrogenado_de_origen_vegetal","Sí/No/En trámite","Ver hoja Materias primas por tipo",1,"Enmiendas","Abono_inorgánico","Enimienda_caliza",null,null,null,"_1.1.4.04_Solución_PK","_2.1.02_Abono_orgánico_nitrogenado_de_origen_vegetal","_3.1.03_Abono_órgano_mineral_nitrogenado_con_lignito_o_leonardita","_4.1.02_Abono_con_aminoácidos","_A.2.1_Escorias_de_deforestación","_5.03_Enmienda_caliza_Carbonato_magnésico_","_6.02_Enmienda_orgánica_Compost","_1.10_Turba_de_Sphagnum","Extracto_de_ajo","Aceite_de_girasol","Sulfato de potasio que puede contener sal de magnesio","Fosfato aluminocálcico","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Leonardita","Leonardita",null,null,"Fosfato aluminocálcico","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas",null,"Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal",null,"Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal",null,"Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal",null,null,null,null,null,null,null,null,"Borato sódico",null,null,null,null,null,null,"Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja","Estiércol de granja",null,null,null,null,null,null,null,null,"Aceite_de_clavo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sí ",null,null,"Etiquetado",null,null,null,null,null,null,"Cambio de nombre "]
["Fertilizante ","Abono orgánico","2.1.03_Abono_orgánico_nitrogenado_de_origen_animal_y_vegetal","Sí/No/En trámite","Ver hoja Materias primas por tipo",3,"Fitosanitarios","Abono_CE",null,null,null,null,null,"_2.1.03_Abono_orgánico_nitrogenado_de_origen_animal_y_vegetal","_3.1.05_Abono_órgano_mineral_nitogenado_líquido_con_turba","_4.1.03_Ácidos_húmicos","_A.2.6_Fosfato_aluminocálcico","_5.04_Enmienda_caliza_Oxido_de_magnesio_magnesita","_6.03_Enmienda_orgánica_Compost_vegetal","_1.11_Turba_herbácea","Aceites_vegetales","Carbón_vegetal_arcilloso",null,"Escorias de defosforación","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Productos o subproducto de origen animal ","Productos o subproducto de origen animal ","Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada",null,null,"Fosfato natural blando","Productos o subproducto de origen animal ","Productos o subproducto de origen animal ","Productos o subproducto de origen animal ","Productos o subproducto de origen animal","Productos o subproducto de origen animal ",null,"Estiércol de granja",null,"Estiércol de granja",null,"Estiércol de granja",null,null,null,null,null,null,null,null,"Borato cálcico",null,null,null,null,null,null,"Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado",null,null,null,null,null,null,null,null,"Aceite_de_colza",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"En_trámite",null,null,"Distribución"]
["Fertilizante ","Abono orgánico","2.2.01_Abono_orgánico_fosfatado_de_origen_animal","Sí/No/En trámite","Ver hoja Materias primas por tipo",4,"Sustancias_básicas","Abono_orgánico",null,null,null,null,null,"_2.2.01_Abono_orgánico_fosfatado_de_origen_animal","_3.2.01_Abono_órgano_mineral_NPK","_4.1.04_Abonos_con_ácidos_húmicos","_A.2.7_Fosfato_roca_blanda",null,"_6.04_Enmienda_orgánica_Compost__de_estiércol","_1.12_Vermicompost_o_húmus_de_lombriz","Arena_de_cuarzo","Cerveza",null,"Sal potásica en bruto","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Producto y subproducto de origen vegetal para abono ","Producto y subproducto de origen vegetal para abono ","Estiércol de granja","Estiércol de granja",null,null,"Escorias de defosforación","Producto y subproducto de origen vegetal para abono ","Producto y subproducto de origen vegetal para abono ","Producto y subproducto de origen vegetal para abono ","Producto y subproducto de origen vegetal para abono ","Producto y subproducto de origen vegetal para abono ",null,"Estiércol desecado y gallinaza deshidratada",null,"Estiércol desecado y gallinaza deshidratada",null,"Estiércol desecado y gallinaza deshidratada",null,null,null,null,null,null,null,null,"Boro etanolamina",null,null,null,null,null,null,"Excrementos líuidos de animales","Excrementos líuidos de animales","Excrementos líuidos de animales","Excrementos líuidos de animales","Excrementos líuidos de animales","Excrementos líuidos de animales","Excrementos líuidos de animales","Excrementos líuidos de animales","Excrementos líuidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales","Excrementos líquidos de animales",null,null,null,null,null,null,null,null,"Aceite_de_menta_verde",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"N/A",null,null,"Producción, envasado y etiquetado "]
["Fertilizante ","Abono orgánico","2.3.01_Abono_orgánico_NPK_de_origen_animal.","Sí/No/En trámite","Ver hoja Materias primas por tipo",5,"Sustrato","Abono_especial",null,null,null,null,null,"_2.3.01_Abono_orgánico_NPK_de_origen_animal","_3.2.02_Abono_órgano_mineral_NPK_con_turba","_4.1.05_Extracto_de_algas_sólido","_A.3.1_Sal_potásica_en_bruto",null,"_6.05_Enmienda_orgánica_Vermicompost","_1.3_Compost_de_estiércol","Azadiractin","Quitosano_Clorhidrato_de_quitosano",null,"Sulfato de potasio que puede contener sal de magnesio","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Proteínas hidrolizadas de origen vegetal ","Proteínas hidrolizadas de origen vegetal ","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado",null,null,"Sal potásica en bruto o kainita","Proteínas hidrolizadas de origen vegetal ","Proteínas hidrolizadas de origen vegetal ","Proteínas hidrolizadas de origen vegetal","Proteínas hidrolizadas de origen vegetal ","Proteínas hidrolizadas de origen vegetal ",null,"Excrementos líquidos de animales",null,"Excrementos líquidos de animales",null,"Excrementos líquidos de animales",null,null,null,null,null,null,null,null,"Abono boratado en solución",null,null,null,null,null,null,"Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano","Guano",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Envasado y etiquetado "]
["Fertilizante ","Abono orgánico","2.3.02_Abono_orgánico_NPK_de_origen_animal_y_vegetal.","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,"Abono_organo_mineral",null,null,null,null,null,"_2.3.02_Abono_orgánico_NPK_de_origen_animal_y_vegetal","_3.2.03_Abono_órgano_mineral_NPK_con_lignito_o_leonardita","_4.1.06_Extracto_de_algas_líquidos","_A.3.6_Sulfato_potásico_con_sales_de_magnesio",null,"_6.06_Enmienda_orgánica_Turba_de_musgo_Tipo_Sphagnum","_1.4_Compost_vegetal","Azufre","Equisetum_arvense_Cola_de_caballo",null,null,"Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados",null,"Algas y productos de algas","Excrementos líuidos de animales","Excrementos líuidos de animales",null,null,"Sulfato de potasio que puede contener sal de magnesio","Algas y productos de algas","Algas y productos de algas","Algas y productos de algas","Algas y productos de algas","Algas y productos de algas",null,"Guano",null,"Guano",null,"Guano",null,null,null,null,null,null,null,null,"Suspensión de abono a base de boro",null,null,null,null,null,null,"Mantillo procedente de cultivo de setas","Mezcla de residuos domésticos compostados o fermentados","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Turba","Turba","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mezcla de residuos domésticos compostados o fermentados","Serrín y virtuas de madera","Turba","Turba","Deyecciones de lombrices e insectos","Mezcla de materias vegetales compostadas o fermentadas","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera"]
["Fertilizante ","Abono orgánico","2.4.01_Abono_orgánico_NP_de_origen_animal.","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,"_2.4.01_Abono_orgánico_NP_de_origen_animal","_3.2.04_Abono_órgano_mineral_NPK_con_o_sin_turba_con_fosfato_roca","_4.1.07a__Abono_sólido_con_extracto_de_algas","_D.1_Sulfato_cálcico",null,"_6.07_Enmienda_orgánica_Turba_herbácea","_2.1_Arcilla","Ceras_","Frutuosa",null,null,"Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Turba","Turba","Turba","Turba","Turba","Turba","Turba","Turba","Turba","Turba","Turba","Turba","Turba","Turba","Turba","Turba","Turba","Turba","Turba","Turba","Turba","Turba","Turba",null,"Ácidos húmicos y fúlvicos","Guano","Guano",null,null,"Carbonato de Calcio","Fosfato aluminocálcico",null,null,"Ácidos húmicos y fúlvicos","Ácidos húmicos y fúlvicos",null,"Mantillo de cortezas",null,"Mantillo de cortezas",null,"Mantillo de cortezas",null,null,null,null,null,null,null,null,"Sal de cobalto",null,null,null,null,null,null,"Deyecciones de lombrices e insectos","Mantillo procedente de cultivo de setas","Mezcla de materias vegetales compostadas o fermentadas","Productos o subproducto de origen animal","Deyecciones de lombrices e insectos","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Mantillo de cortezas","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Producto y subproducto de origen vegetal para abono","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas"]
["Fertilizante ","Abono orgánico","2.4.02_Abono_orgánico_NP_de_origen_animal_y_vegetal.","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,"_2.4.02_Abono_orgánico_NP_de_origen_animal_y_vegetal","_3.3.01_Abono_órgano_mineral_NPK_líquido","_4.1.07b__Abono_líquido_con_extracto_de_algas","_D.2_Solución_de_cloruro_de_calcio",null,"_6.08_Alperujo_desecado","_2.2_Arcilla_cocida","Cerevisane","Lecitina",null,null,"Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas",null,"Fosfato aluminocálcico","Mantillo procedente de cultivo de setas","Mantillo procedente de cultivo de setas",null,null,"Carbonato de Calcio y magnesio","Fosfato natural blando",null,null,"Leonardita","Leonardita",null,"Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado",null,"Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado",null,"Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado",null,null,null,null,null,null,null,null,"Quelato de cobalto",null,null,null,null,null,null,"Mezcla de materias vegetales compostadas o fermentadas","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Producto y subproducto de origen vegetal para abono","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Polvo de roca y arcilla","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Serrín y virtuas de madera","Polvo de roca y arcilla","Polvo de roca y arcilla","Polvo de roca y arcilla","Polvo de roca y arcilla","Polvo de roca y arcilla","Polvo de roca y arcilla"]
["Fertilizante ","Abono orgánico","2.5.01_Abono_orgánico_NK_de_origen_vegetal.","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,"_2.5.01_Abono_orgánico_NK_de_origen_vegetal","_3.3.02_Abono_órgano_mineral_NPK_líquido_con_turba","_4.1.11_Mezcla_sólida_de_aminoácidos_y_extracto_de_algas","_D.3_Azufre_elemental",null,"_6.09_Compost_de_alperujo","_2.3_Arcilla_expandida","Cloruro_de_sodio","Polvo_de_semillas_de_mostaza",null,null,"Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas",null,"Fosfato natural blando","Deyecciones de lombrices e insectos","Deyecciones de lombrices e insectos",null,null,"Sulfato de magnesio","Escorias de defosforación",null,null,"Fosfato aluminocálcico","Fosfato aluminocálcico",null,"Mantillo procedente de cultivo de setas",null,"Mantillo procedente de cultivo de setas",null,"Mantillo procedente de cultivo de setas",null,null,null,null,null,null,null,null,"Solución de abono a base de cobalto",null,null,null,null,null,null,"Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Leonardita","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Leonardita","Leonardita","Serrín y virtuas de madera",null,"Polvo de roca y arcilla","Polvo de roca y arcilla","Polvo de roca y arcilla","Mantillo de cortezas"]
["Fertilizante ","Abono organo_mineral","3.1.02_Abono_órgano_mineral_nitrogenado_con_turba","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,"_3.4.01_Abono_órgano_mineral_NP","_4.1.12_Mezcla_líquida_de_aminoácidos_y_extracto_de_algas","_D.4._Sulfato_de_magnesio",null,null,"_2.4_Arcilla_granulada_","Corteza_de_sauce_salix_cortex","Sacarosa",null,null,"Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal",null,"Escorias de defosforación","Mezcla de materias vegetales compostadas o fermentadas","Mezcla de materias vegetales compostadas o fermentadas",null,null,"Solución de cloruro de calcio","Sal potásica en bruto o kainita",null,null,"Fosfato natural blando","Fosfato natural blando",null,"Mezcla de materias vegetales compostadas o fermentadas",null,"Mezcla de materias vegetales compostadas o fermentadas",null,"Mezcla de materias vegetales compostadas o fermentadas",null,null,null,null,null,null,null,null,"Complejo cobalto",null,null,null,null,null,null,"Productos o subproducto de origen animal","Serrín y virtuas de madera","Serrín y virtuas de madera","Quitina","Leonardita","Leonardita","Leonardita","Quitina","Quitina","Mantillo de cortezas",null,null,null,null,"Polvo de roca y arcilla"]
["Fertilizante ","Abono organo_mineral","3.1.03_Abono_órgano_mineral_nitrogenado_con_lignito_o_leonardita","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,"_3.4.02_Abono_órgano_mineral_NP_con_turba","_4.1.13_Abono_sólido_con_extracto_de_algas_y_aminoácidos","_E._Abonos_inorgánicos_que_contienen_micronutrientes",null,null,"_2.5_Arena_y_gravillas","COS_OGA","Salix_spp_cortex_Corteza_de_sauce",null,null,"Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal",null,"Sal potásica en bruto o kainita","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal",null,null,"Sulfato de calcio (yeso)","Sulfato de potasio que puede contener sal de magnesio",null,null,"Escorias de defosforación","Escorias de defosforación",null,"Mezcla de residuos domésticos compostados o fermentados",null,"Mezcla de residuos domésticos compostados o fermentados",null,"Mezcla de residuos domésticos compostados o fermentados",null,null,null,null,null,null,null,null,"Sal de cobre",null,null,null,null,null,null,"Producto y subproducto de origen vegetal para abono","Mantillo de cortezas","Mantillo de cortezas",null,"Quitina","Quitina","Quitina",null,null,"Polvo de roca y arcilla"]
["Fertilizante ","Abono organo_mineral","3.1.04_Abono_órgano_mineral_nitogenado_líquido","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,"_3.4.03_Abono_órgano_mineral_NP_con_lignito_o_leonardita","_4.1.14_Abono_líquido_con_extracto_de_algas_y_aminoácidos.","_G.1._Enmiendas_naturales",null,null,"_2.6_Arenas_y_gravillas_silíceas","Cuasia_","Suero",null,null,"Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Productos o subproducto de origen animal","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono",null,"Sulfato de potasio que puede contener sal de magnesio","Productos o subproducto de origen animal","Productos o subproducto de origen animal",null,null,"Cal industrial procedente de producción de azúcar","Carbonato de Calcio",null,null,"Sal potásica en bruto o kainita","Sal potásica en bruto o kainita",null,"Producto y subproducto de origen vegetal para abono",null,"Producto y subproducto de origen vegetal para abono",null,"Producto y subproducto de origen vegetal para abono",null,null,null,null,null,null,null,null,"Óxido de cobre",null,null,null,null,null,null,"Leonardita","Leonardita","Leonardita"]
["Fertilizante ","Abono organo_mineral","3.1.05_Abono_órgano_mineral_nitogenado_líquido_con_turba","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,"_3.4.04_Abono_órgano_mineral_NP_con_o_sin_turba_con_fosfato_roca","_4.4.01_Micorrizas","_G.3.1a_y_1b__Caliza_dolomítica_estandar_y_calidad_superior",null,null,null,"Deltametrín_Piretroides","Urtica_spp_Ortiga",null,null,"Quitina","Quitina","Quitina","Quitina","Quitina","Quitina","Quitina","Quitina","Quitina","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera",null,"Carbonato de Calcio","Producto y subproducto de origen vegetal para abono","Producto y subproducto de origen vegetal para abono",null,null,"Azufre elemental","Carbonato de Calcio y magnesio",null,null,"Sulfato de potasio que puede contener sal de magnesio","Sulfato de potasio que puede contener sal de magnesio",null,"Productos o subproducto de origen animal",null,"Productos o subproducto de origen animal",null,"Productos o subproducto de origen animal",null,null,null,null,null,null,null,null,"Hidróxido de cobre",null,null,null,null,null,null,"Quitina","Quitina","Quitina"]
["Fertilizante ","Abono organo_mineral","3.2.01_Abono_órgano_mineral_NPK","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,"_3.5.01__Abono_órgano_mineral_NP_líquido","_4.4.02_Abono_con_micorrizas",null,null,null,null,"Dióxido_de_carbono","Vinagre",null,null,"Residuos moluscos","Residuos moluscos","Residuos moluscos","Residuos moluscos","Residuos moluscos","Residuos moluscos","Residuos moluscos","Residuos moluscos","Residuos moluscos","Turba","Turba","Turba","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas","Mantillo de cortezas",null,"Carbonato de Calcio y magnesio","Quitina","Quitina",null,null,"Ácido Bórico","Sulfato de magnesio",null,null,"Carbonato de Calcio","Carbonato de Calcio",null,"Quitina",null,"Quitina",null,"Quitina",null,null,null,null,null,null,null,null,"Quelato de cobre"]
["Fertilizante ","Abono organo_mineral","3.2.02_Abono_órgano_mineral_NPK_con_turba","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,"_3.5.02__Abono_órgano_mineral_NP_líquido_con_turba","_4.4.03_Microorganismos_no_micorrícicos",null,null,null,null,"Etileno",null,null,null,"Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Serrín y virtuas de madera","Vinaza y extracto de vinaza","Vinaza y extracto de vinaza","Vinaza y extracto de vinaza","Vinaza y extracto de vinaza","Vinaza y extracto de vinaza","Vinaza y extracto de vinaza","Vinaza y extracto de vinaza","Vinaza y extracto de vinaza","Vinaza y extracto de vinaza","Fosfato natural blando","Fosfato natural blando","Leonardita","Fosfato natural blando","Fosfato natural blando","Fosfato natural blando","Vinaza y extracto de vinaza","Vinaza y extracto de vinaza","Vinaza y extracto de vinaza","Vinaza y extracto de vinaza","Vinaza y extracto de vinaza","Fosfato natural blando","Fosfato natural blando","Leonardita","Fosfato natural blando","Fosfato natural blando","Fosfato natural blando",null,"Sulfato de magnesio",null,"Fosfato aluminocálcico",null,null,"Borato sódico","Solución de cloruro de calcio",null,null,"Carbonato de Calcio y magnesio","Carbonato de Calcio y magnesio",null,"Residuos moluscos",null,"Residuos moluscos",null,"Residuos moluscos",null,null,null,null,null,null,null,null,"Abono a base de cobre"]
["Fertilizante ","Abono organo_mineral","3.2.03_Abono_órgano_mineral_NPK_con_lignito_o_leonardita","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,"_3.6.01_Abono_órgano_mineral_NK","_ 4.4.04_Abono_con_microorganismos_no_micorrícicos",null,null,null,null,"Eugenol_terpenos",null,null,null,"Vinaza y extracto de vinaza","Vinaza y extracto de vinaza","Vinaza y extracto de vinaza","Vinaza y extracto de vinaza","Vinaza y extracto de vinaza","Vinaza y extracto de vinaza","Vinaza y extracto de vinaza","Vinaza y extracto de vinaza","Vinaza y extracto de vinaza",null,"Leonardita",null,"Fosfato natural blando","Fosfato natural blando","Leonardita","Fosfato natural blando","Fosfato natural blando","Fosfato natural blando","Fosfato aluminocálcico","Fosfato aluminocálcico","Fosfato natural blando","Fosfato aluminocálcico","Fosfato aluminocálcico","Fosfato aluminocálcico","Sal potásica en bruto","Sal potásica en bruto","Leonardita","Sal potásica en bruto","Sal potásica en bruto","Fosfato aluminocálcico","Fosfato aluminocálcico","Fosfato natural blando","Fosfato aluminocálcico","Fosfato aluminocálcico","Fosfato aluminocálcico",null,"Solución de cloruro de calcio",null,"Fosfato natural blando",null,null,"Borato cálcico","Sulfato de calcio (yeso)",null,null,"Sulfato de magnesio","Sulfato de magnesio",null,"Serrín y virtuas de madera",null,"Serrín y virtuas de madera",null,"Serrín y virtuas de madera",null,null,null,null,null,null,null,null,"Solución de abono a base de cobre"]
["Fertilizante ","Abono organo_mineral","3.2.04_Abono_órgano_mineral_NPK_(con_o_sin_turba)_con_fosfato_roca","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,"_3.6.02_Abono_órgano_mineral_NK_con_turba","_4.4.05_Mezcla_de_microorganismos",null,null,null,null,"Feromonas",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Fosfato aluminocálcico","Fosfato aluminocálcico","Fosfato natural blando","Fosfato aluminocálcico","Fosfato aluminocálcico","Fosfato aluminocálcico","Escorias de defosforación","Escorias de defosforación","Fosfato aluminocálcico","Escorias de defosforación","Escorias de defosforación","Escorias de defosforación","Sulfato de potasio que puede contener sal de magnesio","Sulfato de potasio que puede contener sal de magnesio","Sal potásica en bruto","Sulfato de potasio que puede contener sal de magnesio","Sulfato de potasio que puede contener sal de magnesio","Escorias de defosforación","Escorias de defosforación","Fosfato aluminocálcico","Escorias de defosforación","Escorias de defosforación","Escorias de defosforación",null,"Sulfato de calcio (yeso)",null,"Escorias de defosforación",null,null,"Boro etanolamina","Cal industrial procedente de producción de azúcar",null,null,"Solución de cloruro de calcio","Solución de cloruro de calcio",null,"Vinaza y extracto de vinaza",null,"Vinaza y extracto de vinaza",null,"Vinaza y extracto de vinaza",null,null,null,null,null,null,null,null,"Oxicloruro de cobre"]
["Fertilizante ","Abono organo_mineral","3.3.01_Abono_órgano_mineral_NPK_líquido","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,"_3.6.03__Abono_órgano_mineral_NK_con_lignito_o_leonardita","_4.4.06_Abono_con_microorganismos",null,null,null,null,"Fosfato_diámonico",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Escorias de defosforación","Escorias de defosforación","Fosfato aluminocálcico","Escorias de defosforación","Escorias de defosforación","Escorias de defosforación",null,null,"Escorias de defosforación",null,null,null,null,null,"Sulfato de potasio que puede contener sal de magnesio",null,null,"Sal potásica en bruto","Sal potásica en bruto","Escorias de defosforación","Fosfato natural blando","Sal potásica en bruto","Sal potásica en bruto",null,"Cal industrial procedente de producción de azúcar",null,"Sal potásica en bruto o kainita",null,null,"Abono boratado en solución","Azufre elemental",null,null,"Sulfato de calcio (yeso)","Sulfato de calcio (yeso)",null,"Algas y productos de algas",null,"Algas y productos de algas",null,"Algas y productos de algas",null,null,null,null,null,null,null,null,"Suspensión de abono a base de cobre"]
["Fertilizante ","Abono organo_mineral","3.3.02_Abono_órgano_mineral_NPK_líquido_con_turba","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,"_3.7.01__Abono_órgano_mineral_NK_líquido",null,null,null,null,null,"Fosfato_férrico",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sal potásica en bruto","Sal potásica en bruto","Escorias de defosforación","Sal potásica en bruto","Sal potásica en bruto","Sal potásica en bruto",null,null,null,null,null,null,null,null,null,null,null,"Sulfato de potasio que puede contener sal de magnesio","Sulfato de potasio que puede contener sal de magnesio","Sal potásica en bruto","Fosfato aluminocálcico","Sulfato de potasio que puede contener sal de magnesio","Sulfato de potasio que puede contener sal de magnesio",null,"Azufre elemental",null,"Sulfato de potasio que puede contener sal de magnesio",null,null,"Suspensión de abono a base de boro","Ácido Bórico",null,null,"Cal industrial procedente de producción de azúcar","Cal industrial procedente de producción de azúcar",null,"Ácidos húmicos y fúlvicos",null,"Ácidos húmicos y fúlvicos",null,"Ácidos húmicos y fúlvicos",null,null,null,null,null,null,null,null,"Complejo de cobre"]
["Fertilizante ","Abono organo_mineral","3.4.01_Abono_órgano_mineral_NP","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,"_3.7.02_Abono_órgano_mineral_NK_líquido_con_turba",null,null,null,null,null,"Geraniol_terpenos",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sulfato de potasio que puede contener sal de magnesio","Sulfato de potasio que puede contener sal de magnesio","Sal potásica en bruto","Sulfato de potasio que puede contener sal de magnesio","Sulfato de potasio que puede contener sal de magnesio","Sulfato de potasio que puede contener sal de magnesio",null,null,null,null,null,null,null,null,null,null,null,null,null,"Sulfato de potasio que puede contener sal de magnesio","Escorias de defosforación",null,null,null,"Ácido Bórico",null,"Carbonato de Calcio",null,null,"Sal de cobalto","Borato sódico",null,null,"Azufre elemental","Azufre elemental",null,"Leonardita",null,"Leonardita",null,"Leonardita",null,null,null,null,null,null,null,null,"Sal de hierro"]
["Fertilizante ","Abono organo_mineral","3.4.02_Abono_órgano_mineral_NP_con_turba","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,"_3.8.01_Abono_órgano_mineral_PK",null,null,null,null,null,"Hidrógenocarbonato_de_potasio",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sulfato de potasio que puede contener sal de magnesio",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sal potásica en bruto",null,null,null,"Borato sódico",null,"Carbonato de Calcio y magnesio",null,null,"Quelato de cobalto","Borato cálcico",null,null,"Ácido Bórico","Ácido Bórico",null,"Fosfato natural blando",null,"Fosfato natural blando",null,"Fosfato natural blando",null,null,null,null,null,null,null,null,"Quelato de hierro"]
["Fertilizante ","Abono organo_mineral","3.4.03_Abono_órgano_mineral_NP_con_lignito_o_leonardita","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,"_3.8.02_Abono_órgano_mineral_PK_con_turba",null,null,null,null,null,"Hidróxido_cuprico_Compuesto_de_cobre",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sulfato de potasio que puede contener sal de magnesio",null,null,null,"Borato cálcico",null,"Sulfato de magnesio",null,null,"Solución de abono a base de cobalto","Boro etanolamina",null,null,"Borato sódico","Borato sódico",null,"Fosfato aluminocálcico",null,"Fosfato aluminocálcico",null,"Fosfato aluminocálcico",null,null,null,null,null,null,null,null,"Solución de abono a base de hierro"]
["Fertilizante ","Abono organo_mineral","3.4.04_Abono_órgano_mineral_NP_(con_o_sin_turba)_con_fosfato_roca","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,"_3.8.03_Abono_órgano_mineral_PK_con_lignito_o_leonardita",null,null,null,null,null,"Hidróxido_de_calcio",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Boro etanolamina",null,"Solución de cloruro de calcio",null,null,"Complejo cobalto","Abono boratado en solución",null,null,"Borato cálcico","Borato cálcico",null,"Escorias de defosforación",null,"Escorias de defosforación",null,"Escorias de defosforación",null,null,null,null,null,null,null,null,"Complejo de hierro"]
["Fertilizante ","Abono organo_mineral","3.5.01__Abono_órgano_mineral_NP_líquido","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,"_3.8.04_Abono_órgano_mineral_PK_con_o_sin_turba_con_fosfato_roca",null,null,null,null,null,"Lambda_cihalotrin_piretroides",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Abono boratado en solución",null,"Sulfato de calcio (yeso)",null,null,"Sal de cobre","Suspensión de abono a base de boro",null,null,"Boro etanolamina","Boro etanolamina",null,"Sal potásica en bruto",null,"Sal potásica en bruto",null,"Sal potásica en bruto",null,null,null,null,null,null,null,null,"Sal de manganeso"]
["Fertilizante ","Abono organo_mineral","3.5.02__Abono_órgano_mineral_NP_líquido_con_turba","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,"_3.9.01_Abono_órgano_mineral_PK_líquido",null,null,null,null,null,"Laminarín",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Suspensión de abono a base de boro",null,"Cal industrial procedente de producción de azúcar",null,null,"Óxido de cobre","Sal de cobalto",null,null,"Abono boratado en solución","Abono boratado en solución",null,"Sulfato de potasio que puede contener sal de magnesio",null,"Sulfato de potasio que puede contener sal de magnesio",null,"Sulfato de potasio que puede contener sal de magnesio",null,null,null,null,null,null,null,null,"Quelato de manganeso"]
["Fertilizante ","Abono organo_mineral","3.6.01_Abono_órgano_mineral_NK","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,"_3.9.02_Abono_órgano_mineral_PK_líquido_con_turba",null,null,null,null,null,"Lecitina_de_soja_sustancia_básica_a_base_de_alimentos",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sal de cobalto",null,"Azufre elemental",null,null,"Hidróxido de cobre","Quelato de cobalto",null,null,"Suspensión de abono a base de boro","Suspensión de abono a base de boro",null,"Carbonato de Calcio",null,"Carbonato de Calcio",null,"Carbonato de Calcio",null,null,null,null,null,null,null,null,"Óxido de manganeso"]
["Fertilizante ","Abono organo_mineral","3.6.02_Abono_órgano_mineral_NK_con_turba","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Maltodextrina",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Quelato de cobalto",null,"Ácido Bórico",null,null,"Quelato de cobre","Solución de abono a base de cobalto",null,null,"Sal de cobalto","Sal de cobalto",null,"Carbonato de Calcio y magnesio",null,"Carbonato de Calcio y magnesio",null,"Carbonato de Calcio y magnesio",null,null,null,null,null,null,null,null,"Abono a base de manganeso"]
["Fertilizante ","Abono organo_mineral","3.6.03__Abono_órgano_mineral_NK_con_lignito_o_leonardita","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Microorganismos",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Solución de abono a base de cobalto",null,"Borato sódico",null,null,"Abono a base de cobre","Complejo cobalto",null,null,"Quelato de cobalto","Quelato de cobalto",null,"Sulfato de magnesio",null,"Sulfato de magnesio",null,"Sulfato de magnesio",null,null,null,null,null,null,null,null,"Solución de abono a base de manganeso"]
["Fertilizante ","Abono organo_mineral","3.7.01__Abono_órgano_mineral_NK_líquido","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Oxicloruro_de_cobre_compuesto_de_cobre",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Complejo cobalto",null,"Borato cálcico",null,null,"Solución de abono a base de cobre","Sal de cobre",null,null,"Solución de abono a base de cobalto","Solución de abono a base de cobalto",null,"Solución de cloruro de calcio",null,"Solución de cloruro de calcio",null,"Solución de cloruro de calcio",null,null,null,null,null,null,null,null,"Suspensión de abono a base de manganeso"]
["Fertilizante ","Abono organo_mineral","3.7.02_Abono_órgano_mineral_NK_líquido_con_turba","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Óxido_cuproso_compuesto_de_cobre",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sal de cobre",null,"Boro etanolamina",null,null,"Oxicloruro de cobre","Óxido de cobre",null,null,"Complejo cobalto","Complejo cobalto",null,"Sulfato de calcio (yeso)",null,"Sulfato de calcio (yeso)",null,"Sulfato de calcio (yeso)",null,null,null,null,null,null,null,null,"Complejo de maganeso"]
["Fertilizante ","Abono organo_mineral","3.8.01_Abono_órgano_mineral_PK","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Óxido_de_cobre_compuesto_de_cobre",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Óxido de cobre",null,"Abono boratado en solución",null,null,"Suspensión de abono a base de cobre","Hidróxido de cobre",null,null,"Sal de cobre","Sal de cobre",null,"Cal industrial procedente de producción de azúcar",null,"Cal industrial procedente de producción de azúcar",null,"Cal industrial procedente de producción de azúcar",null,null,null,null,null,null,null,null,"Molibdato sódico"]
["Fertilizante ","Abono organo_mineral","3.8.02_Abono_órgano_mineral_PK_con_turba","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Peróxido_de_hidrógeno",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Hidróxido de cobre",null,"Suspensión de abono a base de boro",null,null,"Complejo de cobre","Quelato de cobre",null,null,"Óxido de cobre","Óxido de cobre",null,"Azufre elemental",null,"Azufre elemental",null,"Azufre elemental",null,null,null,null,null,null,null,null,"Molibdato amónico"]
["Fertilizante ","Abono organo_mineral","3.8.03_Abono_órgano_mineral_PK_con_lignito_o_leonardita","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Piretrinas",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Quelato de cobre",null,"Sal de cobalto",null,null,"Sal de hierro","Abono a base de cobre",null,null,"Hidróxido de cobre","Hidróxido de cobre",null,"Ácido Bórico",null,"Ácido Bórico",null,"Ácido Bórico",null,null,null,null,null,null,null,null,"Abono a base de molibdeno"]
["Fertilizante ","Abono organo_mineral","3.8.04_Abono_órgano_mineral_PK_(con_o_sin_turba)_con_fosfato_roca","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Polisulfuro_de_calcio",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Abono a base de cobre",null,"Quelato de cobalto",null,null,"Quelato de hierro","Solución de abono a base de cobre",null,null,"Quelato de cobre","Quelato de cobre",null,"Borato sódico",null,"Borato sódico",null,"Borato sódico",null,null,null,null,null,null,null,null,"Solución de abono a base de molibdeno"]
["Fertilizante ","Abono organo_mineral","3.9.01_Abono_órgano_mineral_PK_líquido","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Proteínas_hidrolizadas",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Solución de abono a base de cobre",null,"Solución de abono a base de cobalto",null,null,"Solución de abono a base de hierro","Oxicloruro de cobre",null,null,"Abono a base de cobre","Abono a base de cobre",null,"Borato cálcico",null,"Borato cálcico",null,"Borato cálcico",null,null,null,null,null,null,null,null,"Sal de zinc"]
["Fertilizante ","Abono organo_mineral","3.9.02_Abono_órgano_mineral_PK_líquido_con_turba","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Repelente_de_origen_animal_o_vegetal_grasa_de_ovino",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Oxicloruro de cobre",null,"Complejo cobalto",null,null,"Complejo de hierro","Suspensión de abono a base de cobre",null,null,"Solución de abono a base de cobre","Solución de abono a base de cobre",null,"Boro etanolamina",null,"Boro etanolamina",null,"Boro etanolamina",null,null,null,null,null,null,null,null,"Quelato de zinc"]
["Fertilizante ","Abono especial","4.1.01_Aminoácidos.","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sales_potasicas_de_ácidos_grasos_vegetales",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Suspensión de abono a base de cobre",null,"Sal de cobre",null,null,"Sal de manganeso","Complejo de cobre",null,null,"Oxicloruro de cobre","Oxicloruro de cobre",null,"Abono boratado en solución",null,"Abono boratado en solución",null,"Abono boratado en solución",null,null,null,null,null,null,null,null,"Óxido de zinc"]
["Fertilizante ","Abono especial","4.1.02_Abono_con_aminoácidos","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Silicato_de_aluminio._Caolín",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Complejo de cobre",null,"Óxido de cobre",null,null,"Quelato de manganeso","Sal de hierro",null,null,"Suspensión de abono a base de cobre","Suspensión de abono a base de cobre",null,"Suspensión de abono a base de boro",null,"Suspensión de abono a base de boro",null,"Suspensión de abono a base de boro",null,null,null,null,null,null,null,null,"Abono a base de zinc"]
["Fertilizante ","Abono especial","4.1.03_Ácidos_húmicos","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Spinosad",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sal de hierro",null,"Hidróxido de cobre",null,null,"Óxido de manganeso","Quelato de hierro",null,null,"Complejo de cobre","Complejo de cobre",null,"Sal de cobalto",null,"Sal de cobalto",null,"Sal de cobalto",null,null,null,null,null,null,null,null,"Solución de abono a base de zinc"]
["Fertilizante ","Abono especial","4.1.04_Abonos_con_ácidos_húmicos","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sulfato_cuprocálcico_compuesto_de_cobre_caldo_bordelés",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Quelato de hierro",null,"Quelato de cobre",null,null,"Abono a base de manganeso","Solución de abono a base de hierro",null,null,"Sal de hierro","Sal de hierro",null,"Quelato de cobalto",null,"Quelato de cobalto",null,"Quelato de cobalto",null,null,null,null,null,null,null,null,"Suspensión de abono a base de zinc"]
["Fertilizante ","Abono especial","4.1.05_Extracto_de_algas_sólido","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sulfato_tribásico_de_cobre_compuesto_de_cobre",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Solución de abono a base de hierro",null,"Abono a base de cobre",null,null,"Solución de abono a base de manganeso","Complejo de hierro",null,null,"Quelato de hierro","Quelato de hierro",null,"Solución de abono a base de cobalto",null,"Solución de abono a base de cobalto",null,"Solución de abono a base de cobalto",null,null,null,null,null,null,null,null,"Complejo de zinc"]
["Fertilizante ","Abono especial","4.1.06_Extracto_de_algas_líquidos","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Tierra_de_diatomeas_",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Complejo de hierro",null,"Solución de abono a base de cobre",null,null,"Suspensión de abono a base de manganeso","Sal de manganeso",null,null,"Solución de abono a base de hierro","Solución de abono a base de hierro",null,"Complejo cobalto",null,"Complejo cobalto",null,"Complejo cobalto"]
["Fertilizante ","Abono especial","4.1.07a__Abono_sólido_con_extracto_de_algas","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Timol_terpenos",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sal de manganeso",null,"Oxicloruro de cobre",null,null,"Complejo de maganeso","Quelato de manganeso",null,null,"Complejo de hierro","Complejo de hierro",null,"Sal de cobre",null,"Sal de cobre",null,"Sal de cobre"]
["Fertilizante ","Abono especial","4.1.07b__Abono_líquido_con_extracto_de_algas","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Quelato de manganeso",null,"Suspensión de abono a base de cobre",null,null,"Molibdato sódico","Óxido de manganeso",null,null,"Sal de manganeso","Sal de manganeso",null,"Óxido de cobre",null,"Óxido de cobre",null,"Óxido de cobre"]
["Fertilizante ","Abono especial","4.1.11_Mezcla_sólida_de_aminoácidos_y_extracto_de_algas","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Óxido de manganeso",null,"Complejo de cobre",null,null,"Molibdato amónico","Abono a base de manganeso",null,null,"Quelato de manganeso","Quelato de manganeso",null,"Hidróxido de cobre",null,"Hidróxido de cobre",null,"Hidróxido de cobre"]
["Fertilizante ","Abono especial","4.1.12_Mezcla_líquida_de_aminoácidos_y_extracto_de_algas","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Abono a base de manganeso",null,"Sal de hierro",null,null,"Abono a base de molibdeno","Solución de abono a base de manganeso",null,null,"Óxido de manganeso","Óxido de manganeso",null,"Quelato de cobre",null,"Quelato de cobre",null,"Quelato de cobre"]
["Fertilizante ","Abono especial","4.1.13_Abono_sólido_con_extracto_de_algas_y_aminoácidos","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Solución de abono a base de manganeso",null,"Quelato de hierro",null,null,"Solución de abono a base de molibdeno","Suspensión de abono a base de manganeso",null,null,"Abono a base de manganeso","Abono a base de manganeso",null,"Abono a base de cobre",null,"Abono a base de cobre",null,"Abono a base de cobre"]
["Fertilizante ","Abono especial","4.1.14_Abono_líquido_con_extracto_de_algas_y_aminoácidos.","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Suspensión de abono a base de manganeso",null,"Solución de abono a base de hierro",null,null,"Sal de zinc","Complejo de maganeso",null,null,"Solución de abono a base de manganeso","Solución de abono a base de manganeso",null,"Solución de abono a base de cobre",null,"Solución de abono a base de cobre",null,"Solución de abono a base de cobre"]
["Fertilizante ","Abono CE","A.2.6_Fosfato_aluminocálcico","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Complejo de maganeso",null,"Complejo de hierro",null,null,"Quelato de zinc","Molibdato sódico",null,null,"Suspensión de abono a base de manganeso","Suspensión de abono a base de manganeso",null,"Oxicloruro de cobre",null,"Oxicloruro de cobre",null,"Oxicloruro de cobre"]
["Fertilizante ","Abono CE","A.2.7_Fosfato_roca_blanda","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Molibdato sódico",null,"Sal de manganeso",null,null,"Óxido de zinc","Molibdato amónico",null,null,"Complejo de maganeso","Complejo de maganeso",null,"Suspensión de abono a base de cobre",null,"Suspensión de abono a base de cobre",null,"Suspensión de abono a base de cobre"]
["Fertilizante ","Abono CE","A.3.1_Sal_potásica_en_bruto","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Molibdato amónico",null,"Quelato de manganeso",null,null,"Abono a base de zinc","Abono a base de molibdeno",null,null,"Molibdato sódico","Molibdato sódico",null,"Complejo de cobre",null,"Complejo de cobre",null,"Complejo de cobre"]
["Fertilizante ","Abono CE","A.3.6_Sulfato_potásico_con_sales_de_magnesio","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Abono a base de molibdeno",null,"Óxido de manganeso",null,null,"Solución de abono a base de zinc","Solución de abono a base de molibdeno",null,null,"Molibdato amónico","Molibdato amónico",null,"Sal de hierro",null,"Sal de hierro",null,"Sal de hierro"]
["Fertilizante ","Abono CE","D.1_Sulfato_cálcico","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Solución de abono a base de molibdeno",null,"Abono a base de manganeso",null,null,"Suspensión de abono a base de zinc","Sal de zinc",null,null,"Abono a base de molibdeno","Abono a base de molibdeno",null,"Quelato de hierro",null,"Quelato de hierro",null,"Quelato de hierro"]
["Fertilizante ","Abono CE","D.3_Azufre_elemental","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sal de zinc",null,"Solución de abono a base de manganeso",null,null,"Complejo de zinc","Quelato de zinc",null,null,"Solución de abono a base de molibdeno","Solución de abono a base de molibdeno",null,"Solución de abono a base de hierro",null,"Solución de abono a base de hierro",null,"Solución de abono a base de hierro"]
["Fertilizante ","Abono CE","D.4._Solución_de_cloruro_cálcico","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Quelato de zinc",null,"Suspensión de abono a base de manganeso",null,null,null,"Óxido de zinc",null,null,"Sal de zinc","Sal de zinc",null,"Complejo de hierro",null,"Complejo de hierro",null,"Complejo de hierro"]
["Fertilizante ","Abono CE","E._Abonos_inorgánicos_que_contienen_micronutrientes","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Óxido de zinc",null,"Complejo de maganeso",null,null,null,"Abono a base de zinc",null,null,"Quelato de zinc","Quelato de zinc",null,"Sal de manganeso",null,"Sal de manganeso",null,"Sal de manganeso"]
["Fertilizante ","Abono CE","G.1._Enmiendas_naturales","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Abono a base de zinc",null,"Molibdato sódico",null,null,null,"Solución de abono a base de zinc",null,null,"Óxido de zinc","Óxido de zinc",null,"Quelato de manganeso",null,"Quelato de manganeso",null,"Quelato de manganeso"]
["Fertilizante ","Abono CE","G.3.1a_y_1b__Caliza_dolomítica:_estandar_y_calidad_superior","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Solución de abono a base de zinc",null,"Molibdato amónico",null,null,null,"Suspensión de abono a base de zinc",null,null,"Abono a base de zinc","Abono a base de zinc",null,"Óxido de manganeso",null,"Óxido de manganeso",null,"Óxido de manganeso"]
["Fertilizante ","Abono CE","A.2.1_Escorias_de_deforestación","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Suspensión de abono a base de zinc",null,"Abono a base de molibdeno",null,null,null,"Complejo de zinc",null,null,"Solución de abono a base de zinc","Solución de abono a base de zinc",null,"Abono a base de manganeso",null,"Abono a base de manganeso",null,"Abono a base de manganeso"]
["Enmiendas","Enimienda caliza","5.01_Enmienda_caliza_Suspensión_de_cal_y_magnesio.","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Complejo de zinc",null,"Solución de abono a base de molibdeno",null,null,null,null,null,null,"Suspensión de abono a base de zinc","Suspensión de abono a base de zinc",null,"Solución de abono a base de manganeso",null,"Solución de abono a base de manganeso",null,"Solución de abono a base de manganeso"]
["Enmiendas","Enimienda caliza","5.02_Enmienda_caliza_Margas.","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sal de zinc",null,null,null,null,null,null,"Complejo de zinc","Complejo de zinc",null,"Suspensión de abono a base de manganeso",null,"Suspensión de abono a base de manganeso",null,"Suspensión de abono a base de manganeso"]
["Enmiendas","Enimienda caliza","5.03_Enmienda_caliza_Carbonato_magnésico._","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Quelato de zinc",null,null,null,null,null,null,null,null,null,"Complejo de maganeso",null,"Complejo de maganeso",null,"Complejo de maganeso"]
["Enmiendas","Enimienda caliza","5.04_Enmienda_caliza_Oxido_de_magnesio_(magnesita)","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Óxido de zinc",null,null,null,null,null,null,null,null,null,"Molibdato sódico",null,"Molibdato sódico",null,"Molibdato sódico"]
["Enmiendas","Enimenda orgánica","6.01_Enmienda_orgánica_húmica.","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Abono a base de zinc",null,null,null,null,null,null,null,null,null,"Molibdato amónico",null,"Molibdato amónico",null,"Molibdato amónico"]
["Enmiendas","Enimenda orgánica","6.02_Enmienda_orgánica_Compost.","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Solución de abono a base de zinc",null,null,null,null,null,null,null,null,null,"Abono a base de molibdeno",null,"Abono a base de molibdeno",null,"Abono a base de molibdeno"]
["Enmiendas","Enimenda orgánica","6.03_Enmienda_orgánica_Compost_vegetal","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Suspensión de abono a base de zinc",null,null,null,null,null,null,null,null,null,"Solución de abono a base de molibdeno",null,"Solución de abono a base de molibdeno",null,"Solución de abono a base de molibdeno"]
["Enmiendas","Enimenda orgánica","6.04_Enmienda_orgánica_Compost__de_estiércol.","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Complejo de zinc",null,null,null,null,null,null,null,null,null,"Sal de zinc",null,"Sal de zinc",null,"Sal de zinc"]
["Enmiendas","Enimenda orgánica","6.05_Enmienda_orgánica_Vermicompost","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Quelato de zinc",null,"Quelato de zinc",null,"Quelato de zinc"]
["Enmiendas","Enimenda orgánica","6.06_Enmienda_orgánica_Turba_de_musgo_Tipo_Sphagnum","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Óxido de zinc",null,"Óxido de zinc",null,"Óxido de zinc"]
["Enmiendas","Enimenda orgánica","6.07_Enmienda_orgánica_Turba_herbácea.","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Abono a base de zinc",null,"Abono a base de zinc",null,"Abono a base de zinc"]
["Enmiendas","Enimenda orgánica","6.08_Alperujo_desecado.","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Solución de abono a base de zinc",null,"Solución de abono a base de zinc",null,"Solución de abono a base de zinc"]
["Enmiendas","Enimenda orgánica","6.09_Compost_de_alperujo.","Sí/No/En trámite","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Suspensión de abono a base de zinc",null,"Suspensión de abono a base de zinc",null,"Suspensión de abono a base de zinc"]
["Sustrato","Sustrato","1.1_Compost","N/A","Ver hoja Materias primas por tipo",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Complejo de zinc",null,"Complejo de zinc",null,"Complejo de zinc"]
["Sustrato","Sustrato","1.3_Compost_de_estiércol","N/A","Ver hoja Materias primas por tipo"]
["Sustrato","Sustrato","1.10_Turba_de_Sphagnum","N/A","Ver hoja Materias primas por tipo"]
["Sustrato","Sustrato","1.11_Turba_herbácea","N/A","Ver hoja Materias primas por tipo"]
["Sustrato","Sustrato","1.12_Vermicompost_o_húmus_de_lombriz","N/A","Ver hoja Materias primas por tipo"]
["Sustrato","Sustrato","1.4_Compost_vegetal","N/A","Ver hoja Materias primas por tipo"]
["Sustrato","Sustrato","2.1_Arcilla","N/A","Ver hoja Materias primas por tipo"]
["Sustrato","Sustrato","2.2_Arcilla_cocida","N/A","Ver hoja Materias primas por tipo"]
["Sustrato","Sustrato","2.3_Arcilla_expandida","N/A","Ver hoja Materias primas por tipo"]
["Sustrato","Sustrato","2.4_Arcilla_granulada_","N/A","Ver hoja Materias primas por tipo"]
["Sustrato","Sustrato","2.5_Arena_y_gravillas","N/A","Ver hoja Materias primas por tipo"]
["Sustrato","Sustrato","2.6_Arenas_y_gravillas_silíceas","N/A","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Extracto_de_ajo","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Azadiractin","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Ceras_(cera_de_abejas)","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","COS_OGA","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Proteínas_hidrolizadas","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Laminarín","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Maltodextrina","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Feromonas","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Aceites_vegetales/aceite_de_colza","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Piretrinas","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Cuasia_","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Repelente_de_origen_animal_o_vegetal_grasa_de_ovino","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Corteza_de_sauce_(salix_cortex)","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Eugenol_(terpenos)","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Geraniol_(terpenos)","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Timol_(terpenos)","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Lecitina_de_soja_(sustancia_básica_a_base_de_alimentos)","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Microorganismos","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Spinosad","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Cerevisane","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Silicato_de_aluminio._Caolín","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Hidróxido_de_calcio","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Dióxido_de_carbono","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Hidróxido_cuprico_(Compuesto_de_cobre)","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Oxicloruro_de_cobre_(compuesto_de_cobre)","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Óxido_cuproso_(compuesto_de_cobre)","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Óxido_de_cobre_(compuesto_de_cobre)","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Sulfato_cuprocálcico_(compuesto_de_cobre)_(caldo_bordelés)","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Sulfato_tribásico_de_cobre_(compuesto_de_cobre)","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Fosfato_diámonico","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Etileno","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Sales_potasicas_de_ácidos_grasos_vegetales","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Fosfato_férrico","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Peróxido_de_hidrógeno","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Tierra_de_diatomeas_","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Polisulfuro_de_calcio","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Aceite_de_parafina","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Hidrógenocarbonato_de_potasio","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Deltametrín_(Piretroides)","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Lambda_cihalotrin_(piretroides)","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Arena_de_cuarzo","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Cloruro_de_sodio","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Fitosanitarios","Fitosanitario","Azufre","Sí/No/En trámite","Ver hoja Materias primas por tipo"]
["Sustancias básicas","Sustancia_básicas","Sustancias_básicas","N/A"]
["Fertilizante ","Abono inorgánico","1.1.3.01_Solución potásica","N/A"]
["Fertilizante ","Abono inorgánico","1.1.4.04_Solución PK","N/A"]

{"sheet":"Hoja2","index":4,"n_rows":38,"n_cols":8,"rows_kept":38,"cut":false,"hidden":true,"merged":[[0,0,0,5]]}
["FERTILIZANTE",null,null,null,null,null,"SUSTRATO","FITOSANITARIO"]
["TIPO 2 ABONO ORGÁNICO","TIPO 3 ABONO ORGANO-MINERAL","TIPO 4 ABONO ESPECIAL","TIPO 5 ENMIENDAS CALIZAS","TIPO 6 ENMIENDAS ORGÁNICAS","ABONO CE","SUSTRATO","FITOSANITARIO"]
["Estiércol de granja","Estiércol de granja","Mezcla de materias vegetales compostadas o fermentadas","Carbonato de Calcio y magnesio (5.02)","Estiércol de granja","Fosfato natural blando (A.2.7)","Estiércol de granja (1.1 y 1.3)","Allium sativum (Extracto de ajo)"]
["Estiércol desecado y gallinaza deshidratada","Estiércol desecado y gallinaza deshidratada","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Carbonato de Calcio y magnesio (5.03 y 5.04)","Estiércol desecado y gallinaza deshidratada","Fosfato aluminocálcico (A.2.6)","Estiércol desecado y gallinaza deshidratada (1.1 y 1.3)","Azadiractina extraída de Azadirachta indica (árbol"]
["Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Productos o subproducto de origen animal (4.1.01 y 4.1.02)",null,"Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado","Escorias de defosforación (A.2.1)","Mantillo de excrementos sólidos, includios la gallinaza y estiércol compostado (1.1 y 1.3)","del neem)"]
["Excrementos líuidos de animales","Excrementos líuidos de animales","Producto y subproducto de origen vegetal para abono (4.1.01 y 4.1.02)",null,"Excrementos líuidos de animales","Sal potásica en bruto o kainita (A. 3.1)","Excrementos líquidos de animales (1.1 y 1.3)","Cera de abejas"]
["Guano","Guano","Proteínas hidrolizadas de origen vegetal (4.1.01 y 4.1.02)",null,"Guano","Sulfato de potasio que puede contener sal de magnesio (A.3.6)","Guano (1.1 y 1.3)","Sustancia activa COS-OGA"]
["Mezcla de residuos domésticos compostados o fermentados","Mezcla de residuos domésticos compostados o fermentados","Algas y productos de algas",null,"Mezcla de residuos domésticos compostados o fermentados (6.01 y 6.02)","Carbonato de Calcio (G.1)","Mezcla de residuos domésticos compostados o fermentados (1.1)","Proteínas hidrolizadas salvo la gelatina"]
["Mantillo procedente de cultivo de setas","Turba","Ácidos húmicos y fúlvicos",null,"Turba (6.06 y 6.07)","Carbonato de Calcio y magnesio (G.1)","Turba (1.10 y 1.11)","Laminarina"]
["Mezcla de materias vegetales compostadas o fermentadas","Mantillo procedente de cultivo de setas",null,null,"Mantillo procedente de cultivo de setas","Sulfato de magnesio (D.4)","Deyecciones de lombrices e insectos (1.12)","Maltodextrina"]
["Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal","Mezcla de materias vegetales compostadas o fermentadas",null,null,"Deyecciones de lombrices e insectos (6.05)","Solución de cloruro de calcio (D.2)","Mezcla de materias vegetales compostadas o fermentadas (1.4)","Feromonas"]
["Productos o subproducto de origen animal","Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal",null,null,"Mezcla de materias vegetales compostadas o fermentadas (6.01 y 6.03)","Sulfato de calcio (yeso) (D.1)","Productos o subproducto de origen animal (1.1)","Aceites vegetales"]
["Producto y subproducto de origen vegetal para abono","Productos o subproducto de origen animal",null,null,"Digerido biogás, con subproductos animales codigeridos con material de origen vegetal o animal (6.01)","Cal industrial procedente de producción de azúcar (G.3.1a y 1b)","Producto y subproducto de origen vegetal para abono (1.1 y 1.4)","Piretrinas"]
["Serrín y virtuas de madera","Producto y subproducto de origen vegetal para abono",null,null,"Productos o subproducto de origen animal","Azufre elemental (D.3)","Serrín y virtuas de madera (1.1.1, 1.1.4 y 1.1.9)","Cuasia extraída de Quassia amara"]
["Mantillo de cortezas","Serrín y virtuas de madera",null,null,"Producto y subproducto de origen vegetal para abono",null,"Mantillo de cortezas  (1.1.1, 1.1.4 y 1.1.9)","Repelentes (por el olor) de origen animal o vegetal / grasa de ovino­"]
["Vinaza y extracto de vinaza (2.5.01)","Mantillo de cortezas",null,null,"Serrín y virtuas de madera (6.02 y 6.03)",null,"Polvo de roca y arcilla (2.1 a 2.6)","Salix spp. Cortex (también denominado corteza de sauce)"]
["Residuos moluscos","Vinaza y extracto de vinaza (3.3 Y 3.7)",null,null,"Mantillo de cortezas (6.02 y 6.03)",null,null,"Terpenos (eugenol, geraniol y timol)"]
["Quitina","Residuos moluscos",null,null,"Leonardita",null,null,"Sustancias básicas a base de alimentos (en particular: lecitinas, sacarosa, fructosa, vinagre, lactosuero, clorhidrato de quitosano  y Equisetum arvense, etc."]
[null,"Quitina",null,null,"Quitina",null,null,"Microorganismos"]
[null,null,null,null,null,null,null,"Spinosad"]
[null,null,null,null,null,null,null,"Cerevisane"]
[null,null,null,null,null,null,null,"Silicato de aluminio (caolín)"]
[null,null,null,null,null,null,null,"Hidróxido de calcio"]
[null,null,null,null,null,null,null,"Dióxido de carbono"]
[null,null,null,null,null,null,null,"Compuestos de cobre en forma de: hidróxido de cobre, cloruro de cobre, óxido de cobre, caldo bordelés y sulfato tribásico de cobre"]
[null,null,null,null,null,null,null,"Fosfato diamónico"]
[null,null,null,null,null,null,null,"Etileno"]
[null,null,null,null,null,null,null,"Ácidos grasos"]
[null,null,null,null,null,null,null,"Fosfato férrico [ortofosfato de hierro (III)]"]
[null,null,null,null,null,null,null,"Peróxido de hidrógeno"]
[null,null,null,null,null,null,null,"Kieselgur (tierra de diatomeas)"]
[null,null,null,null,null,null,null,"Polisulfuro de calcio"]
[null,null,null,null,null,null,null,"Aceite de parafina"]
[null,null,null,null,null,null,null,"Hidrogenocarbonato de potasio y sodio (también denomi­nado bicarbonato de potasio y sodio)"]
[null,null,null,null,null,null,null,"Piretroides (solo deltametrina o lambda-cihalotrina)"]
[null,null,null,null,null,null,null,"Arena de cuarzo"]
[null,null,null,null,null,null,null,"Cloruro de sodio"]
[null,null,null,null,null,null,null,"Azufre"]

{"sheet":"Proveedores","index":5,"n_rows":3,"n_cols":3,"rows_kept":3,"cut":false,"hidden":false,"merged":[[0,0,0,2],[1,0,2,0],[1,1,2,1],[1,2,2,2]]}
["Fecha última actualización: "]
["Nombre Proveedor \n(De materia prima o producto elaborado)","Materia prima","Marca Comercial producto final"]
[null,"Materia prima","Marca Comercial producto final"]

{"sheet":"Resumen Productos ","index":6,"n_rows":19,"n_cols":6,"rows_kept":19,"cut":false,"hidden":false,"merged":[[0,0,0,3]]}
["CUMPLIMENTACIÓN POR SOHISCERT "]
["Alcance/s solicitado/s",null,null,{"$f":"IF(AND(E2=TRUE,F2=TRUE),\"UNE315500:2017-UNE142500:2017\",IF(F2=TRUE,\"UNE142500:2017\",IF(E2=TRUE,\"UNE315500:2017\",\"\")))","v":""},false,false]
["Tipo de producción",null,null,{"$f":"IF(E3=TRUE,\"Mixta\",IF(F3=TRUE,\"Solo insumo para producción ecológica\",\"ERROR\"))","v":"ERROR"},false,false]
["Nº de instalaciones propias",null,null,{"$f":"'Datos Generales'!C31","v":1}]
["Subcontratación",null,null,{"$f":"IF(AND(E5=TRUE,F5=TRUE),\"ERROR\",IF(E5=TRUE,\"SI\",IF(F5=TRUE,\"NO\",\"ERROR\")))","v":"ERROR"},false,false]
["Nº de productos total",null,null,{"$f":"COUNTA(Productos!D5:D126)","v":0}]
["Tipos de productos","Número","Registro (SI/NO)"]
["Abono_CE",{"$f":"COUNTIF(Productos!$E$5:$E$105,\"Abono_CE\")","v":0}]
["Abono orgánico",{"$f":"COUNTIF(Productos!$E$5:$E$105,\"Abono_orgánico\")","v":0}]
["Abono órgano-mineral",{"$f":"COUNTIF(Productos!$E$5:$E$105,\"Abono_organo_mineral\")","v":0}]
["Abono especial",{"$f":"COUNTIF(Productos!$E$5:$E$105,\"Abono_especial\")","v":0}]
["Enmienda orgánica",{"$f":"COUNTIF(Productos!$E$5:$E$105,\"Enimenda_orgánica\")","v":0}]
["Enmienda caliza",{"$f":"COUNTIF(Productos!$E$5:$E$105,\"Enimienda_caliza\")","v":0}]
["Sustrato",{"$f":"COUNTIF(Productos!$E$5:$E$105,\"Sustrato_\")","v":0}]
["Fitosanitario",{"$f":"COUNTIF(Productos!$E$5:$E$105,\"Fitosanitarios_\")","v":0}]
["Sustancia Básica",{"$f":"COUNTIF(Productos!$E$5:$E$105,\"Sustancias_básicas_\")","v":0}]
["Proveedores"]
["Nº proveedores materias primas",{"$f":"COUNTA(#REF!)","v":1}]
["Nº proveedores de producto compuesto",{"$f":"COUNTA(#REF!)","v":1}]